{"id":859825,"date":"2023-04-13T23:47:12","date_gmt":"2023-04-13T23:47:12","guid":{"rendered":"https:\/\/www.renovarpapeles.com\/tramites\/?p=859825"},"modified":"2023-04-13T23:47:12","modified_gmt":"2023-04-13T23:47:12","slug":"www-sube-gob-arregistro-dar-de-alta-la-tarjeta","status":"publish","type":"post","link":"https:\/\/www.renovarpapeles.com\/tramites\/www-sube-gob-arregistro-dar-de-alta-la-tarjeta\/","title":{"rendered":"Dar de ALTA Tarjeta SUBE www.sube.gob.ar\/registro"},"content":{"rendered":"<div class=\"intro-text\">\n<p>Constantemente andamos en transporte p\u00fablico, por eso decidimos comprar el carnet de pasaje, pero deseamos conocer c\u00f3mo <b>Dar de alta Tarjeta SUBE<\/b> para poder emplearla y obtener sus beneficios.<\/p>\n<\/div>\n<p><img wpfc-lazyload-disable=\"true\" decoding=\"async\" src=\"https:\/\/www.renovarpapeles.com\/tramites\/wp-content\/uploads\/2013\/02\/tarjeta-sube.jpg\" alt=\"Dar de Alta tarjeta SUBE\" width=\"100%\" height=\"673\" title=\"\"><\/p>\n<p>Esta tarjeta es la que nos permite cancelar nuestro pasaje en las unidades de transporte que pertenecen al sistema p\u00fablico, incluyendo el tren, el metro, transporte terrestre y mar\u00edtimo adscrito.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>El pl\u00e1stico tiene un precio alrededor de 90 pesos, adquiri\u00e9ndolo en cualquier establecimiento avalado por la empresa SUBE. Adem\u00e1s, cada tarjeta incluye un c\u00f3digo \u00fanico en la parte trasera, que la hace intransferible.<\/p>\n<p>\ud83d\udc49\u00a0Te puede interesar <a href=\"https:\/\/www.renovarpapeles.com\/tramites\/tramite-n-of-ident-como-saber-el-mio\/\">Tramite N\u00ba of Ident no es correcto<\/a>.<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_81 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Contenidos<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #333333;color:#333333\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #333333;color:#333333\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.renovarpapeles.com\/tramites\/www-sube-gob-arregistro-dar-de-alta-la-tarjeta\/#%C2%BFComo_Dar_de_alta_a_la_Tarjeta_SUBE\" >\u00bfC\u00f3mo Dar de alta a la Tarjeta SUBE?<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.renovarpapeles.com\/tramites\/www-sube-gob-arregistro-dar-de-alta-la-tarjeta\/#Via_web\" >V\u00eda web<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.renovarpapeles.com\/tramites\/www-sube-gob-arregistro-dar-de-alta-la-tarjeta\/#App_SUBE\" >App SUBE<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.renovarpapeles.com\/tramites\/www-sube-gob-arregistro-dar-de-alta-la-tarjeta\/#Llamada_telefonica\" >Llamada telef\u00f3nica<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.renovarpapeles.com\/tramites\/www-sube-gob-arregistro-dar-de-alta-la-tarjeta\/#Centro_de_atencion\" >Centro de atenci\u00f3n<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.renovarpapeles.com\/tramites\/www-sube-gob-arregistro-dar-de-alta-la-tarjeta\/#Beneficios_de_dar_de_alta_la_tarjeta_SUBE\" >Beneficios de dar de alta la tarjeta SUBE<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFComo_Dar_de_alta_a_la_Tarjeta_SUBE\"><\/span>\u00bfC\u00f3mo Dar de alta a la Tarjeta SUBE?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Al recibir la tarjeta de transporte, lo adecuado es registrarla a nuestro nombre, para que el sistema reconozca quien es el titular de la misma, esto facilita que en caso de robo o p\u00e9rdida, se logre cancelar el pl\u00e1stico anterior y as\u00ed transferir el saldo a una nueva, sin perder un peso.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Para darnos de alta en nuestra tarjeta SUBE, podemos realizarlos empleando alguno de los siguientes canales que se han puesto a disposici\u00f3n de los usuarios.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Via_web\"><\/span><b>V\u00eda web<\/b><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Al ingresar a la direcci\u00f3n <strong>www.tarjetasube.sube.gob.ar<\/strong> entraremos a una p\u00e1gina donde nos aparecer\u00e1 una ventana con un formulario de ingreso, debajo de este apartado se visualizar\u00e1 un bot\u00f3n que dice \u201cReg\u00edstrate Ahora\u201d, seleccionamos esta opci\u00f3n.<\/p>\n<p>\u2705\u00a0<strong>www.tarjetasube.sube.gob.ar<\/strong><\/p>\n<p>\u2705\u00a0<strong>www.sube.gob.ar\/registro<\/strong><\/p>\n<p>Luego apareceremos en una p\u00e1gina donde se debe rellenar un cuestionario que nos pide colocar el n\u00famero de la tarjeta SUBE que se encuentra en la parte posterior, los d\u00edgitos de DNI, y un correo electr\u00f3nico personal que se encuentre activo (este se a\u00f1ade dos veces para confirmar).<\/p>\n<p>Presionamos la opci\u00f3n \u201cContinuar\u201d y aterrizaremos en otro portal en donde debemos crear una clave de 4 d\u00edgitos, que tambi\u00e9n se repite en dos ocasiones, para confirmaci\u00f3n del sistema.<\/p>\n<p>A\u00fan nuestra tarjeta no est\u00e1 totalmente de alta, debemos esperar que el sistema nos env\u00ede un correo electr\u00f3nico con una direcci\u00f3n web, que seleccionaremos para as\u00ed corroborar nuestro registro en el programa SUBE.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"App_SUBE\"><\/span><b>App SUBE<\/b><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Una alternativa tecnol\u00f3gica que nos permite registrarnos es instalando la aplicaci\u00f3n telef\u00f3nica SUBE en nuestro equipo inteligente, desde ah\u00ed podemos efectuar todo el procedimiento, con solo tener conexi\u00f3n a Internet.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Llamada_telefonica\"><\/span><b>Llamada telef\u00f3nica<\/b><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>El sistema SUBE pensando en cada una de las opciones m\u00e1s f\u00e1ciles y disponibles para sus usuarios, coloc\u00f3 a disposici\u00f3n del p\u00fablico el n\u00famero 0800-777-7823 (SUBE), que le permite a los beneficiarios dar de alta a la tarjeta, coloc\u00e1ndola a su nombre.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Para realizar esta acci\u00f3n es necesario que tenga a la mano el DNI y la tarjeta.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Centro_de_atencion\"><\/span><b>Centro de atenci\u00f3n<\/b><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Es una de las formas m\u00e1s f\u00e1ciles de efectuar el registro a nuestro nombre de la tarjeta SUBE, en caso de no tener acceso a Internet o a un tel\u00e9fono, podemos acercarnos a un centro de atenci\u00f3n SUBE, donde un trabajador de la empresa nos solicitar\u00e1 el DNI y pl\u00e1stico, para darnos de alta en el sistema.<\/p>\n<p>Debemos anotar y guardar nuestra clave de usuario SUBE, que nos permite ingresar al sistema y poder revisar nuestro perfil. En caso de olvidarla, la p\u00e1gina ofrece una opci\u00f3n para restituirla.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Beneficios_de_dar_de_alta_la_tarjeta_SUBE\"><\/span>Beneficios de dar de alta la tarjeta SUBE<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Poder tener un perfil en el sistema SUBE nos permite chequear: la cantidad de viajes disponibles, los descuentos que se encuentren ofertando y el dinero que tenemos disponible.<\/p>\n<p>En caso de consumir todos los viajes y dinero que ten\u00eda en su tarjeta, el programa SUBE nos permite emplearla hasta un l\u00edmite de 72 pesos, proporcion\u00e1ndonos un lapso de tiempo para poder recargar, evitando que dejemos de utilizarla.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>E incluso SUBE ofrece una modalidad de subsidio para todos aquellos usuarios que forman parte de los planes sociales de la ANSES, reduciendo los costos de cobro por viaje.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Constantemente andamos en transporte p\u00fablico, por eso decidimos comprar el carnet de pasaje, pero deseamos conocer c\u00f3mo Dar de&#8230;<\/p>\n","protected":false},"author":1,"featured_media":3396745,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[22,27],"tags":[],"class_list":["post-859825","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-argentina","category-tarjeta-sube"],"uagb_featured_image_src":{"full":["https:\/\/www.renovarpapeles.com\/tramites\/wp-content\/uploads\/2013\/02\/tarjeta-sube.jpg",906,673,false],"thumbnail":["https:\/\/www.renovarpapeles.com\/tramites\/wp-content\/uploads\/2013\/02\/tarjeta-sube-150x150.jpg",150,150,true],"medium":["https:\/\/www.renovarpapeles.com\/tramites\/wp-content\/uploads\/2013\/02\/tarjeta-sube.jpg",300,223,false],"medium_large":["https:\/\/www.renovarpapeles.com\/tramites\/wp-content\/uploads\/2013\/02\/tarjeta-sube.jpg",768,570,false],"large":["https:\/\/www.renovarpapeles.com\/tramites\/wp-content\/uploads\/2013\/02\/tarjeta-sube.jpg",906,673,false],"1536x1536":["https:\/\/www.renovarpapeles.com\/tramites\/wp-content\/uploads\/2013\/02\/tarjeta-sube.jpg",906,673,false],"2048x2048":["https:\/\/www.renovarpapeles.com\/tramites\/wp-content\/uploads\/2013\/02\/tarjeta-sube.jpg",906,673,false]},"uagb_author_info":{"display_name":"Renovar Papeles","author_link":"https:\/\/www.renovarpapeles.com\/tramites\/author\/admin\/"},"uagb_comment_info":39,"uagb_excerpt":"Constantemente andamos en transporte p\u00fablico, por eso decidimos comprar el carnet de pasaje, pero deseamos conocer c\u00f3mo Dar de...","_links":{"self":[{"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/posts\/859825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/comments?post=859825"}],"version-history":[{"count":0,"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/posts\/859825\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/media\/3396745"}],"wp:attachment":[{"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/media?parent=859825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/categories?post=859825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/tags?post=859825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}