{"id":651534,"date":"2024-02-17T11:35:51","date_gmt":"2024-02-17T11:35:51","guid":{"rendered":"https:\/\/www.renovarpapeles.com\/tramites\/?p=651534"},"modified":"2024-02-17T11:34:25","modified_gmt":"2024-02-17T11:34:25","slug":"ver-mi-solicitud-con-el-numero-de-referencia-tarjeta-sanitaria-europea","status":"publish","type":"post","link":"https:\/\/www.renovarpapeles.com\/tramites\/ver-mi-solicitud-con-el-numero-de-referencia-tarjeta-sanitaria-europea\/","title":{"rendered":"Ver mi Solicitud con el Numero de Referencia Tarjeta Sanitaria Europea"},"content":{"rendered":"<span id=\"euroSanitaria\">\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Contenidos<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #333333;color:#333333\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #333333;color:#333333\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.renovarpapeles.com\/tramites\/ver-mi-solicitud-con-el-numero-de-referencia-tarjeta-sanitaria-europea\/#%C2%BFComo_ver_mi_solicitud_de_Tarjeta_Sanitaria_Europea_con_el_numero_de_referencia\" >\u00bfC\u00f3mo ver mi solicitud de Tarjeta Sanitaria Europea con el n\u00famero de referencia?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.renovarpapeles.com\/tramites\/ver-mi-solicitud-con-el-numero-de-referencia-tarjeta-sanitaria-europea\/#%C2%BFQue_es_la_Tarjeta_Sanitaria_Europea\" >\u00bfQu\u00e9 es la Tarjeta Sanitaria Europea?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.renovarpapeles.com\/tramites\/ver-mi-solicitud-con-el-numero-de-referencia-tarjeta-sanitaria-europea\/#%C2%BFComo_solicitar_la_Tarjeta_Sanitaria_Europea\" >\u00bfC\u00f3mo solicitar la Tarjeta Sanitaria Europea?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.renovarpapeles.com\/tramites\/ver-mi-solicitud-con-el-numero-de-referencia-tarjeta-sanitaria-europea\/#%C2%BFComo_ver_mi_solicitud_con_el_numero_de_referencia\" >\u00bfC\u00f3mo ver mi solicitud con el n\u00famero de referencia?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.renovarpapeles.com\/tramites\/ver-mi-solicitud-con-el-numero-de-referencia-tarjeta-sanitaria-europea\/#%C2%BFQue_informacion_puedo_encontrar_en_mi_solicitud_de_TSE\" >\u00bfQu\u00e9 informaci\u00f3n puedo encontrar en mi solicitud de TSE?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.renovarpapeles.com\/tramites\/ver-mi-solicitud-con-el-numero-de-referencia-tarjeta-sanitaria-europea\/#Recomendaciones_finales\" >Recomendaciones finales<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFComo_ver_mi_solicitud_de_Tarjeta_Sanitaria_Europea_con_el_numero_de_referencia\"><\/span>\u00bfC\u00f3mo ver mi solicitud de Tarjeta Sanitaria Europea con el n\u00famero de referencia?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Si has solicitado una Tarjeta Sanitaria Europea (TSE) para poder recibir atenci\u00f3n m\u00e9dica en otro pa\u00eds de la Uni\u00f3n Europea, es importante que puedas realizar un seguimiento de tu solicitud. Para ello, es necesario que tengas a mano el n\u00famero de referencia que se te proporcion\u00f3 al hacer la solicitud. En este art\u00edculo te explicaremos paso a paso c\u00f3mo puedes acceder a tu solicitud de TSE utilizando el n\u00famero de referencia y qu\u00e9 informaci\u00f3n encontrar\u00e1s en el proceso.<\/p>\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFQue_es_la_Tarjeta_Sanitaria_Europea\"><\/span>\u00bfQu\u00e9 es la Tarjeta Sanitaria Europea?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>La Tarjeta Sanitaria Europea es un documento que te permite recibir atenci\u00f3n m\u00e9dica en otro pa\u00eds de la Uni\u00f3n Europea en caso de necesidad. Este documento es gratuito y su validez es de dos a\u00f1os desde su expedici\u00f3n. Para poder solicitar la TSE es necesario ser ciudadano de un pa\u00eds miembro de la UE, del Espacio Econ\u00f3mico Europeo (EEE) o de Suiza. Tambi\u00e9n pueden solicitarla los ciudadanos de terceros pa\u00edses con residencia legal en la UE.<\/p>\n\n<p>La TSE cubre los mismos servicios m\u00e9dicos que recibir\u00edas si estuvieras en tu pa\u00eds de origen, de acuerdo a la legislaci\u00f3n del pa\u00eds donde te encuentres. Es importante tener en cuenta que esta tarjeta no cubre servicios m\u00e9dicos que hayas buscado de forma intencional, es decir, no puedes viajar a otro pa\u00eds para recibir una atenci\u00f3n m\u00e9dica espec\u00edfica que no est\u00e9 contemplada por la TSE.<\/p>\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFComo_solicitar_la_Tarjeta_Sanitaria_Europea\"><\/span>\u00bfC\u00f3mo solicitar la Tarjeta Sanitaria Europea?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>La solicitud de la Tarjeta Sanitaria Europea se puede realizar de manera presencial, por tel\u00e9fono o a trav\u00e9s de internet. Si decides hacerlo de forma online, debes acceder a la p\u00e1gina web de la Seguridad Social de tu pa\u00eds y seguir los pasos que te indiquen. Si la haces de forma presencial o por tel\u00e9fono, debes acudir a tu centro de atenci\u00f3n primaria o a la oficina de la Seguridad Social correspondiente para realizar la solicitud.<\/p>\n\n<p>Al completar el tr\u00e1mite de solicitud, recibir\u00e1s un n\u00famero de referencia que es imprescindible para poder acceder a los detalles de tu expediente. A continuaci\u00f3n, te explicamos c\u00f3mo hacerlo.<\/p>\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFComo_ver_mi_solicitud_con_el_numero_de_referencia\"><\/span>\u00bfC\u00f3mo ver mi solicitud con el n\u00famero de referencia?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Para poder ver el estado de tu solicitud de forma online, debes acceder a la p\u00e1gina web del Instituto Nacional de la Seguridad Social (INSS) de tu pa\u00eds. A continuaci\u00f3n, selecciona la opci\u00f3n \u00abTarjeta Sanitaria Europea\u00bb y dentro de ella, la opci\u00f3n \u00abSolicitar cita previa\u00bb. Dependiendo del pa\u00eds, el nombre de esta opci\u00f3n puede variar.<\/p>\n\n<p>Una vez est\u00e9s en la p\u00e1gina de cita previa, deber\u00e1s introducir tu n\u00famero de referencia y la fecha de nacimiento. A continuaci\u00f3n, te mostrar\u00e1 el estado actual de tu solicitud. Si a\u00fan no est\u00e1 disponible, significa que el tr\u00e1mite se encuentra en proceso y debes esperar unos d\u00edas m\u00e1s para poder acceder a la informaci\u00f3n.<\/p>\n\n<p>Si tu solicitud ha sido aprobada, podr\u00e1s descargar o imprimir una copia provisional de la TSE. Esta es v\u00e1lida por un per\u00edodo de 90 d\u00edas desde su emisi\u00f3n y servir\u00e1 para que puedas recibir atenci\u00f3n m\u00e9dica en el pa\u00eds que hayas indicado en tu solicitud.<\/p>\n\n<p>Tambi\u00e9n puedes obtener informaci\u00f3n sobre tu solicitud llamando al tel\u00e9fono de informaci\u00f3n europeo 112. Este tel\u00e9fono es gratuito y est\u00e1 disponible las 24 horas del d\u00eda. All\u00ed podr\u00e1s obtener informaci\u00f3n sobre como proceder en caso de que necesites una atenci\u00f3n m\u00e9dica urgente durante tu estancia en el extranjero.<\/p>\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFQue_informacion_puedo_encontrar_en_mi_solicitud_de_TSE\"><\/span>\u00bfQu\u00e9 informaci\u00f3n puedo encontrar en mi solicitud de TSE?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Una vez hayas accedido a la informaci\u00f3n sobre tu solicitud, podr\u00e1s conocer el estado en el que se encuentra y los datos asociados. Entre ellos, podr\u00e1s encontrar:<\/p>\n\n<ul>\n <li>Fecha y hora de tu solicitud<\/li>\n <li>Nombre y apellidos del solicitante<\/li>\n <li>Fecha de nacimiento<\/li>\n <li>Pa\u00eds de residencia<\/li>\n <li>Fecha de validez de la TSE<\/li>\n<\/ul>\n\n<p>Tambi\u00e9n podr\u00e1s ver si la solicitud ha sido aprobada o rechazada y, en caso de rechazo, conocer el motivo del mismo. Recuerda que el tiempo de procesamiento de tu solicitud puede variar en funci\u00f3n del pa\u00eds al que vayas a viajar.<\/p>\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Recomendaciones_finales\"><\/span>Recomendaciones finales<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Es importante que revises la informaci\u00f3n de tu solicitud de TSE con regularidad, ya que esto te permitir\u00e1 estar al tanto de su estado y de posibles cambios o requerimientos por parte de la entidad correspondiente. Si has recibido una atenci\u00f3n m\u00e9dica durante tu estancia en otro pa\u00eds, es importante que conserves todos los recibos y facturas relacionados, ya que podr\u00e1s ser reembolsado por los gastos m\u00e9dicos a tu regreso.<\/p>\n\n<p>No olvides que la Tarjeta Sanitaria Europea no es un sustituto del seguro de viaje, por lo que te recomendamos contar con uno antes de partir a cualquier pa\u00eds. De esta forma, podr\u00e1s tener una mayor cobertura y tranquilidad durante tu viaje.<\/p>\n\n<p>En resumen, si necesitas ver el estado de tu solicitud de Tarjeta Sanitaria Europea, puedes hacerlo utilizando el n\u00famero de referencia que se te proporcion\u00f3 al hacerla. Esta informaci\u00f3n la podr\u00e1s obtener de forma online o a trav\u00e9s del tel\u00e9fono de informaci\u00f3n europeo. Esperamos que esta gu\u00eda te sea de ayuda y que puedas disfrutar de un viaje seguro y tranquilo en cualquier pa\u00eds de la Uni\u00f3n Europea.<\/p>\n<\/span>","protected":false},"excerpt":{"rendered":"<p>\u00bfC\u00f3mo ver mi solicitud de Tarjeta Sanitaria Europea con el n\u00famero de referencia? Si has solicitado una Tarjeta Sanitaria&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-651534","post","type-post","status-publish","format-standard","hentry","category-tramites"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"Renovar Papeles","author_link":"https:\/\/www.renovarpapeles.com\/tramites\/author\/admin\/"},"uagb_comment_info":0,"uagb_excerpt":"\u00bfC\u00f3mo ver mi solicitud de Tarjeta Sanitaria Europea con el n\u00famero de referencia? Si has solicitado una Tarjeta Sanitaria...","_links":{"self":[{"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/posts\/651534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/comments?post=651534"}],"version-history":[{"count":0,"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/posts\/651534\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/media?parent=651534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/categories?post=651534"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/tags?post=651534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}