{"id":607579,"date":"2023-03-01T18:22:48","date_gmt":"2023-03-01T18:22:48","guid":{"rendered":"https:\/\/www.renovarpapeles.com\/tramites\/?p=607579"},"modified":"2023-03-01T18:22:48","modified_gmt":"2023-03-01T18:22:48","slug":"como-rellenar-modelo-790-codigo-012-expedicion-de-tarjeta-de-residencia","status":"publish","type":"post","link":"https:\/\/www.renovarpapeles.com\/tramites\/como-rellenar-modelo-790-codigo-012-expedicion-de-tarjeta-de-residencia\/","title":{"rendered":"Como Rellenar Modelo 790 Codigo 012 Expedici\u00f3n de Tarjeta de Residencia"},"content":{"rendered":"<p>El modelo 790, c\u00f3digo 012, es un formulario espec\u00edfico para expedici\u00f3n de tarjeta de residencia para ciudadanos extranjeros legalmente establecidos en Espa\u00f1a. El procedimiento es el siguiente: el interesado, a trav\u00e9s de la p\u00e1gina web de la Administraci\u00f3n, debe rellenar el modelo 790, c\u00f3digo 012, donde se detallar\u00e1 la informaci\u00f3n solicitada: apellidos, nombre, n\u00famero de pasaporte, domicilio, documento de identidad o NIE, entre otros. Una vez que el formulario est\u00e9 debidamente rellenado, se deber\u00e1 adjuntar una copia del pasaporte y de la documentaci\u00f3n migratoria expedida por la Direcci\u00f3n General de Fronteras y Extranjer\u00eda, as\u00ed como una fotograf\u00eda actual del interesado. <\/p>\n<p>Una vez recibida la solicitud debidamente cumplimentada y con los documentos necesarios, la Administraci\u00f3n iniciar\u00e1 los tr\u00e1mites de preinscripci\u00f3n, que una vez concluidos y superadas las pruebas de control de identidad, se emitir\u00e1 la tarjeta de residencia. El titular deber\u00e1 recoger la tarjeta de residencia, present\u00e1ndose con el original de los documentos originales adjuntos a la solicitud, en la Direcci\u00f3n General de Fronteras y Extranjer\u00eda, donde se le entregar\u00e1 la tarjeta y la documentaci\u00f3n pertinente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El modelo 790, c\u00f3digo 012, es un formulario espec\u00edfico para expedici\u00f3n de tarjeta de residencia para ciudadanos extranjeros legalmente&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[5,16],"tags":[],"class_list":["post-607579","post","type-post","status-publish","format-standard","hentry","category-expedientes","category-tarjeta-residencia"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"Renovar Papeles","author_link":"https:\/\/www.renovarpapeles.com\/tramites\/author\/admin\/"},"uagb_comment_info":0,"uagb_excerpt":"El modelo 790, c\u00f3digo 012, es un formulario espec\u00edfico para expedici\u00f3n de tarjeta de residencia para ciudadanos extranjeros legalmente...","_links":{"self":[{"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/posts\/607579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/comments?post=607579"}],"version-history":[{"count":0,"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/posts\/607579\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/media?parent=607579"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/categories?post=607579"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/tags?post=607579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}