{"id":3515829,"date":"2025-04-08T10:06:51","date_gmt":"2025-04-08T10:06:51","guid":{"rendered":"https:\/\/www.renovarpapeles.com\/tramites\/?p=3515829"},"modified":"2025-04-08T19:08:10","modified_gmt":"2025-04-08T19:08:10","slug":"deduccion-compra-ordenador-en-la-rioja-2011","status":"publish","type":"post","link":"https:\/\/www.renovarpapeles.com\/tramites\/deduccion-compra-ordenador-en-la-rioja-2011\/","title":{"rendered":"DEDUCCION COMPRA ORDENADOR EN LA RIOJA 2011"},"content":{"rendered":"En la Comunidad Aut\u00f3noma de La Rioja, existe una deducci\u00f3n en el Impuesto sobre la Renta de las Personas F\u00edsicas (IRPF) para aquellos contribuyentes que hayan adquirido un ordenador durante el a\u00f1o 2011. Esta deducci\u00f3n est\u00e1 regulada en la Ley 10\/2009, de 22 de diciembre, de medidas fiscales y administrativas para el a\u00f1o 2010.<\/p><!-- \/wp:post-content --><!-- wp:paragraph --><p>La cantidad de la deducci\u00f3n ser\u00e1 del 15% del importe del ordenador, con un l\u00edmite m\u00e1ximo de 300 euros por contribuyente. Es importante destacar que esta deducci\u00f3n solo se aplica a la compra de un \u00fanico ordenador, no siendo aplicable en caso de adquisici\u00f3n de m\u00e1s de uno.<\/p><!-- \/wp:paragraph --><!-- wp:paragraph --><p>","protected":false},"excerpt":{"rendered":"<p>En la Comunidad Aut\u00f3noma de La Rioja, existe una deducci\u00f3n en el Impuesto sobre la Renta de las Personas&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[265],"tags":[270],"class_list":["post-3515829","post","type-post","status-publish","format-standard","hentry","category-renta","tag-renta-2011"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"Renovar Papeles","author_link":"https:\/\/www.renovarpapeles.com\/tramites\/author\/admin\/"},"uagb_comment_info":0,"uagb_excerpt":"En la Comunidad Aut\u00f3noma de La Rioja, existe una deducci\u00f3n en el Impuesto sobre la Renta de las Personas...","_links":{"self":[{"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/posts\/3515829","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/comments?post=3515829"}],"version-history":[{"count":0,"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/posts\/3515829\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/media?parent=3515829"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/categories?post=3515829"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/tags?post=3515829"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}