{"id":3145226,"date":"2023-12-20T04:04:11","date_gmt":"2023-12-20T04:04:11","guid":{"rendered":"https:\/\/www.renovarpapeles.com\/tramites\/?p=3145226"},"modified":"2023-12-20T04:04:11","modified_gmt":"2023-12-20T04:04:11","slug":"httpsrecibos-cusaem-gob-mx","status":"publish","type":"post","link":"https:\/\/www.renovarpapeles.com\/tramites\/httpsrecibos-cusaem-gob-mx\/","title":{"rendered":"https:\/\/recibos.cusaem.gob.mx"},"content":{"rendered":"<div class=\"intro-text\">CUSAEM es una nueva agencia de seguridad privada en la Ciudad de M\u00e9xico que ofrece servicios de alta calidad, profesionales, las 24 horas del d\u00eda y con una amplia y continua capacitaci\u00f3n para todo el personal de seguridad asignado a la empresa.\n<\/div>\n<p><\/p>\n<p>El Cuerpo de Seguridad Auxiliar del Estado de M\u00e9xico es un nuevo cuerpo de polic\u00eda federal. Se sit\u00faa entre los departamentos de polic\u00eda municipales y la Polic\u00eda Federal. Este cuerpo fue creado para atender los problemas de seguridad p\u00fablica a nivel estatal y municipal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CUSAEM es una nueva agencia de seguridad privada en la Ciudad de M\u00e9xico que ofrece servicios de alta calidad,&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[228,21],"tags":[],"class_list":["post-3145226","post","type-post","status-publish","format-standard","hentry","category-cusaem","category-mexico"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"Renovar Papeles","author_link":"https:\/\/www.renovarpapeles.com\/tramites\/author\/admin\/"},"uagb_comment_info":0,"uagb_excerpt":"CUSAEM es una nueva agencia de seguridad privada en la Ciudad de M\u00e9xico que ofrece servicios de alta calidad,...","_links":{"self":[{"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/posts\/3145226","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/comments?post=3145226"}],"version-history":[{"count":0,"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/posts\/3145226\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/media?parent=3145226"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/categories?post=3145226"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/tags?post=3145226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}