{"id":2304277,"date":"2024-02-18T11:42:29","date_gmt":"2024-02-18T11:42:29","guid":{"rendered":"https:\/\/www.renovarpapeles.com\/tramites\/?p=2304277"},"modified":"2024-02-18T11:34:27","modified_gmt":"2024-02-18T11:34:27","slug":"como-llenar-hoja-nat-del-inss","status":"publish","type":"post","link":"https:\/\/www.renovarpapeles.com\/tramites\/como-llenar-hoja-nat-del-inss\/","title":{"rendered":"COMO LLENAR HOJA NAT DEL INSS"},"content":{"rendered":"<p>\nLa hoja NAT del INSS es uno de los documentos m\u00e1s importantes para los trabajadores en Espa\u00f1a, ya que es el comprobante oficial de sus cotizaciones a la Seguridad Social. Este formulario es necesario para realizar una gran variedad de tr\u00e1mites, como solicitar una prestaci\u00f3n o jubilaci\u00f3n, pedir un certificado de cotizaciones, entre otros. Es por ello que es fundamental conocer c\u00f3mo llenar adecuadamente esta hoja. En este art\u00edculo, como expertos en tr\u00e1mites online, te explicaremos paso a paso c\u00f3mo llevar a cabo este proceso de manera sencilla y eficiente.\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Contenidos<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #333333;color:#333333\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #333333;color:#333333\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.renovarpapeles.com\/tramites\/como-llenar-hoja-nat-del-inss\/#%C2%BFQue_es_el_formulario_NAT_del_INSS\" >\u00bfQu\u00e9 es el formulario NAT del INSS?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.renovarpapeles.com\/tramites\/como-llenar-hoja-nat-del-inss\/#%C2%BFComo_obtener_la_hoja_NAT_del_INSS\" >\u00bfC\u00f3mo obtener la hoja NAT del INSS?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.renovarpapeles.com\/tramites\/como-llenar-hoja-nat-del-inss\/#%C2%BFComo_llenar_la_hoja_NAT_del_INSS\" >\u00bfC\u00f3mo llenar la hoja NAT del INSS?<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.renovarpapeles.com\/tramites\/como-llenar-hoja-nat-del-inss\/#1_Datos_personales\" >1. Datos personales<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.renovarpapeles.com\/tramites\/como-llenar-hoja-nat-del-inss\/#2_Datos_de_la_empresa\" >2. Datos de la empresa<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.renovarpapeles.com\/tramites\/como-llenar-hoja-nat-del-inss\/#3_Datos_del_contrato\" >3. Datos del contrato<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/www.renovarpapeles.com\/tramites\/como-llenar-hoja-nat-del-inss\/#4_Datos_de_cotizacion\" >4. Datos de cotizaci\u00f3n<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/www.renovarpapeles.com\/tramites\/como-llenar-hoja-nat-del-inss\/#5_Liquidacion_de_cotizaciones\" >5. Liquidaci\u00f3n de cotizaciones<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/www.renovarpapeles.com\/tramites\/como-llenar-hoja-nat-del-inss\/#Conclusion\" >Conclusi\u00f3n<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFQue_es_el_formulario_NAT_del_INSS\"><\/span>\u00bfQu\u00e9 es el formulario NAT del INSS?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n<p>Antes de comenzar a explicar c\u00f3mo llenar la hoja NAT del INSS, es importante entender en qu\u00e9 consiste este formulario. La sigla NAT significa \u00abN\u00famero de Afiliaci\u00f3n al Trabajador\u00bb y se refiere a un c\u00f3digo asignado por la Tesorer\u00eda General de la Seguridad Social a cada trabajador en Espa\u00f1a. Este n\u00famero es \u00fanico e intransferible, y es utilizado para identificar y gestionar las cotizaciones de cada persona al sistema de la Seguridad Social.<\/p>\n\n<p>El formulario NAT del INSS es un documento que recoge todo el historial de cotizaciones de un trabajador, es decir, sus aportaciones a la Seguridad Social realizadas durante toda su vida laboral. Este documento es necesario en m\u00faltiples situaciones, como por ejemplo cuando se va a solicitar una pensi\u00f3n de jubilaci\u00f3n, ya que se requiere demostrar un m\u00ednimo de cotizaciones para acceder a ella. Adem\u00e1s, tambi\u00e9n puede ser necesario para obtener ciertos beneficios sociales o para acreditar la vida laboral, entre otros tr\u00e1mites.<\/p>\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFComo_obtener_la_hoja_NAT_del_INSS\"><\/span>\u00bfC\u00f3mo obtener la hoja NAT del INSS?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n<p>La hoja NAT del INSS se puede obtener de manera presencial en cualquier oficina de la Seguridad Social, presentando el documento de identidad y el n\u00famero de afiliaci\u00f3n al trabajador. Sin embargo, en la actualidad, este tr\u00e1mite se puede realizar de manera m\u00e1s r\u00e1pida y sencilla a trav\u00e9s de la sede electr\u00f3nica del INSS.<\/p>\n\n<p>Para ello, es necesario contar con un certificado digital o un usuario y contrase\u00f1a en la plataforma Cl@ve. Con estas herramientas, podr\u00e1s acceder al servicio de <a href=\"\" target=\"_blank\" rel=\"noopener\">Descarga del informe de vida laboral<\/a>, donde se incluye la hoja NAT del INSS.<\/p>\n\n<p>Una vez en la plataforma, deber\u00e1s ingresar tu usuario y contrase\u00f1a o seleccionar el certificado digital correspondiente. Una vez dentro, selecciona la opci\u00f3n \u00abVida laboral\u00bb y completa los datos que te soliciten, como tu n\u00famero de afiliaci\u00f3n y tu DNI. Al finalizar, podr\u00e1s descargar la hoja NAT del INSS en formato PDF.<\/p>\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFComo_llenar_la_hoja_NAT_del_INSS\"><\/span>\u00bfC\u00f3mo llenar la hoja NAT del INSS?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n<p>Una vez descargada la hoja NAT del INSS, es necesario completar algunos campos con informaci\u00f3n personal y laboral. A continuaci\u00f3n, te explicamos c\u00f3mo llenar cada secci\u00f3n de esta hoja de forma detallada.<\/p>\n\n<h3><span class=\"ez-toc-section\" id=\"1_Datos_personales\"><\/span>1. Datos personales<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p>En la primera secci\u00f3n de la hoja NAT del INSS, deber\u00e1s completar tus datos personales, como tu nombre completo, DNI, direcci\u00f3n y n\u00famero de tel\u00e9fono. Adem\u00e1s, deber\u00e1s indicar tu estado civil, si est\u00e1s casado\/a o soltero\/a.<\/p>\n\n<h3><span class=\"ez-toc-section\" id=\"2_Datos_de_la_empresa\"><\/span>2. Datos de la empresa<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p>En la siguiente secci\u00f3n, se deben incluir los datos de la empresa en la que est\u00e1s trabajando o en la que has prestado servicios. Para ello, deber\u00e1s proporcionar el nombre o raz\u00f3n social de la empresa, su c\u00f3digo de cuenta de cotizaci\u00f3n, que se puede encontrar en tu n\u00f3mina, y la direcci\u00f3n completa de la misma.<\/p>\n\n<h3><span class=\"ez-toc-section\" id=\"3_Datos_del_contrato\"><\/span>3. Datos del contrato<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p>En esta parte, se deben indicar los datos de tu contrato de trabajo, como la fecha de inicio y fin, el tipo de contrato y la categor\u00eda profesional. Tambi\u00e9n se debe incluir la duraci\u00f3n y la jornada semanal o mensual.<\/p>\n\n<h3><span class=\"ez-toc-section\" id=\"4_Datos_de_cotizacion\"><\/span>4. Datos de cotizaci\u00f3n<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p>Esta secci\u00f3n es una de las m\u00e1s importantes de la hoja NAT del INSS, ya que es donde se deben indicar todas las cotizaciones realizadas durante el periodo de duraci\u00f3n del contrato. Para ello, es necesario contar con un informe de cotizaciones emitido por la empresa, en el que se detallan las aportaciones realizadas por el trabajador y por la empresa para cada periodo.<\/p>\n\n<p>En la hoja NAT del INSS, se deben incluir los siguientes datos:<\/p>\n\n<ul>\n <li>Base de cotizaci\u00f3n: se refiere al salario percibido por el trabajador y que sirve de base para calcular las aportaciones a la Seguridad Social.<\/li>\n <li>Cuota obrera: es la aportaci\u00f3n que realiza el trabajador a la Seguridad Social, que se calcula en funci\u00f3n de su salario.<\/li>\n <li>Cuota empresarial: es la aportaci\u00f3n que realiza la empresa a la Seguridad Social, que se calcula en funci\u00f3n del salario del trabajador.<\/li>\n <li>Prorrata: algunos conceptos salariales, como pluses o comisiones, no se incluyen en la base de cotizaci\u00f3n, por lo que deben prorratearse para tener una base de cotizaci\u00f3n total.<\/li>\n<\/ul>\n\n<p>Se deben indicar estas cantidades para cada mes del periodo de duraci\u00f3n del contrato, incluyendo un total al final de la secci\u00f3n.<\/p>\n\n<h3><span class=\"ez-toc-section\" id=\"5_Liquidacion_de_cotizaciones\"><\/span>5. Liquidaci\u00f3n de cotizaciones<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p>En la \u00faltima secci\u00f3n, se deben incluir las cantidades que se han pagado por las cotizaciones en cada periodo, tanto por parte del trabajador como de la empresa. La cantidad indicada debe coincidir con la suma de las cuotas obrera y empresarial indicadas en la secci\u00f3n anterior.<\/p>\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Conclusion\"><\/span>Conclusi\u00f3n<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n<p>Como puedes ver, llenar la hoja NAT del INSS no es algo complicado, pero requiere seguir una serie de pasos y tener a mano cierta informaci\u00f3n. Si tienes cualquier duda, siempre puedes acudir a un experto en tr\u00e1mites online para que te ayude en el proceso. Recuerda que este documento es muy importante y debe estar bien cumplimentado para evitar problemas futuros en tus tr\u00e1mites con la Seguridad Social.<\/p>\n\n<p>En resumen, para obtener la hoja NAT del INSS debes acceder a la sede electr\u00f3nica del INSS con un certificado digital o usuario y contrase\u00f1a en Cl@ve, y completar los datos que te soliciten. Luego, deber\u00e1s llenar cada secci\u00f3n de la hoja con tus datos personales, de la empresa, del contrato y de cotizaci\u00f3n. Finalmente, revisa que toda la informaci\u00f3n est\u00e9 correcta y completa.<\/p>\n\n<p>Esperamos que este art\u00edculo te haya sido de utilidad y que ya sepas c\u00f3mo llenar la hoja NAT del INSS de forma adecuada para tus tr\u00e1mites. Recuerda que, gracias a la tecnolog\u00eda, cada vez es m\u00e1s f\u00e1cil realizar este tipo de gestiones de manera online, lo que nos permite ahorrar tiempo y recursos. \u00a1No dudes en utilizar estos medios para facilitar tus tr\u00e1mites con la Seguridad Social!<\/p>","protected":false},"excerpt":{"rendered":"<p>La hoja NAT del INSS es uno de los documentos m\u00e1s importantes para los trabajadores en Espa\u00f1a, ya que&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-2304277","post","type-post","status-publish","format-standard","hentry","category-tramites"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"Renovar Papeles","author_link":"https:\/\/www.renovarpapeles.com\/tramites\/author\/admin\/"},"uagb_comment_info":0,"uagb_excerpt":"La hoja NAT del INSS es uno de los documentos m\u00e1s importantes para los trabajadores en Espa\u00f1a, ya que...","_links":{"self":[{"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/posts\/2304277","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/comments?post=2304277"}],"version-history":[{"count":0,"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/posts\/2304277\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/media?parent=2304277"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/categories?post=2304277"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/tags?post=2304277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}