{"id":2301456,"date":"2023-10-11T18:08:42","date_gmt":"2023-10-11T18:08:42","guid":{"rendered":"https:\/\/www.renovarpapeles.com\/tramites\/?p=2301456"},"modified":"2023-10-11T18:08:42","modified_gmt":"2023-10-11T18:08:42","slug":"reporte-de-extravio-efectivale","status":"publish","type":"post","link":"https:\/\/www.renovarpapeles.com\/tramites\/reporte-de-extravio-efectivale\/","title":{"rendered":"Reporte de Extravio Efectivale"},"content":{"rendered":"<div class=\"intro-text\">Recuerde que si no utiliza todo el importe de su tarjeta de prestaciones en una sola compra, devu\u00e9lvanosla para que podamos d\u00e1rsela a otra persona que la necesite. No pagues con tu tarjeta Efectivale en tiendas o supermercados.\n<\/div>\n<p><\/p>\n<p>Sabes que vas a querer tener m\u00e1s dinero en tu tarjeta. A continuaci\u00f3n te explicamos c\u00f3mo consultar tu saldo r\u00e1pidamente por Internet: Visita http:\/\/www.efectivalecheck.com y accede a tu cuenta. Haz clic en \u00abMi cuenta\u00bb en la parte superior derecha y luego en \u00abVer saldo\u00bb en la parte inferior de la p\u00e1gina.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Recuerde que si no utiliza todo el importe de su tarjeta de prestaciones en una sola compra, devu\u00e9lvanosla para&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[162],"tags":[],"class_list":["post-2301456","post","type-post","status-publish","format-standard","hentry","category-efectivale"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"Renovar Papeles","author_link":"https:\/\/www.renovarpapeles.com\/tramites\/author\/admin\/"},"uagb_comment_info":0,"uagb_excerpt":"Recuerde que si no utiliza todo el importe de su tarjeta de prestaciones en una sola compra, devu\u00e9lvanosla para...","_links":{"self":[{"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/posts\/2301456","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/comments?post=2301456"}],"version-history":[{"count":0,"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/posts\/2301456\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/media?parent=2301456"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/categories?post=2301456"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.renovarpapeles.com\/tramites\/wp-json\/wp\/v2\/tags?post=2301456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}